{"id":688107,"date":"2026-06-03T06:00:18","date_gmt":"2026-06-03T04:00:18","guid":{"rendered":"https:\/\/blog.wiwo.de\/management\/?p=688107"},"modified":"2026-06-03T02:05:03","modified_gmt":"2026-06-03T00:05:03","slug":"wenn-rueckforderungen-von-coronahilfen-zum-sargnagel-fuer-haendler-und-unternehmen-werden","status":"publish","type":"post","link":"https:\/\/blog.wiwo.de\/management\/2026\/06\/03\/wenn-rueckforderungen-von-coronahilfen-zum-sargnagel-fuer-haendler-und-unternehmen-werden\/","title":{"rendered":"Wenn R\u00fcckforderungen von Coronahilfen zum Sargnagel f\u00fcr H\u00e4ndler und Unternehmen werden"},"content":{"rendered":"<header>\n<h1 class=\"wrapper\">Staat fordert Coronahilfen zur\u00fcck \u2013 so wehren sich Betriebe<\/h1>\n<div class=\"wrapper\">Will der Staat unerwartet pl\u00f6tzlich Coronahilfen zur\u00fcck, kann dies Kleinbetriebe ruinieren. Anw\u00e4lte zeigen, wie sie sich wehren.<\/div>\n<div><\/div>\n<div class=\"wrapper\"><a class=\"ng-star-inserted\" title=\"\" href=\"https:\/\/www.wiwo.de\/autoren\/claudia-toedtmann\/4625522.html\" target=\"_self\">(zuerst erschienen in der gedruckten WirtschaftsWoche am <\/a>29.05.2026)<\/div>\n<div class=\"wrapper\">\n<div class=\"toolbar\">\n<div class=\"ng-star-inserted\"><\/div>\n<\/div>\n<\/div>\n<\/header>\n<div class=\"grid large-layout\">\n<div class=\"storyline-image\">\n<p><button class=\"no-label\" type=\"button\" aria-label=\"\u00d6ffnen\"><\/button><img decoding=\"async\" title=\"\" src=\"https:\/\/images.wiwo.de\/-C0il7I5yvoS\/cover\/760\/507\/195\/194\/0\/0\/0.5\/0.5\/aufmacherbild-kanzleien-fuer-restrukturierungs-und-insolvenzrecht.jpeg\" alt=\"\" \/><\/p>\n<div><span class=\"credits\">Foto: Ulf K.\/Sepia<\/span><\/div>\n<\/div>\n<\/div>\n<div class=\"wrapper paywall-position-top\">\n<div data-placement=\"pos_marg_right_1\"><\/div>\n<div class=\"aside-wrapper-element ng-star-inserted\">\n<div>\n<p>Drei Jahre nachdem eine Rheinl\u00e4nderin 9.000 Euro Coronasoforthilfe erhalten hatte, forderte das Land Nordrhein-Westfalen sie zur\u00fcck, per R\u00fcckforderungsbescheid vom 8. Dezember 2023. Die Frau sollte den Brief noch rechtzeitig vor Jahresende bekommen, damit die Forderung nicht verj\u00e4hrte. Doch die Post schaffte es nicht, den Brief zuzustellen, schickte ihn der Beh\u00f6rde mit dem Stempel \u201eun\u00adbekannt verzogen\u201c zur\u00fcck. Erst im neuen Jahr, am 8. Januar 2024, einen Monat nachdem der Bescheid erlassen worden war, erhielt die Frau den R\u00fcckforderungsbescheid, diesmal per E-Mail.<\/p>\n<\/div>\n<\/div>\n<div class=\"aside-wrapper-element ng-star-inserted\">\n<div>\n<h1>Coronahilfen-R\u00fcckforderung: Formfehler als Rettung<\/h1>\n<\/div>\n<\/div>\n<div class=\"aside-wrapper-element ng-star-inserted\">\n<div>\n<p>Das war ihr Gl\u00fcck: \u201eDieses Datum ihrer Kenntnisnahme war entscheidend, die Zustellung des Bescheids erfolgte acht Tage zu sp\u00e4t \u2013 ein Formfehler mit erfreulichen Folgen f\u00fcr die Kl\u00e4gerin\u201c, erkl\u00e4rt Insolvenzverwalter Malte K\u00f6ster. Die Frau klagte beim Verwaltungsgericht K\u00f6ln gegen den Bescheid und siegte. Nicht, weil Bescheid rechtswidrig gewesen w\u00e4re \u2013 er war in Ordnung. Sondern weil ihr Anwalt aufmerksam genug war, die Daten zu pr\u00fcfen, sich auf die Verj\u00e4hrung berief und die Forderung dann nicht durchsetzbar war (Akten\u00adzeichen 16 K 703\/24).<\/p>\n<div id=\"attachment_683965\" style=\"width: 160px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-683965\" class=\"size-thumbnail wp-image-683965\" src=\"https:\/\/blog.wiwo.de\/management\/files\/2024\/02\/koester.malte_.kleiner-e1780444354292-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><p id=\"caption-attachment-683965\" class=\"wp-caption-text\">Malte K\u00f6ster (Foto: C.T\u00f6dtmann)<\/p><\/div>\n<\/div>\n<\/div>\n<div class=\"aside-wrapper-element ng-star-inserted\">\n<div>\n<p>Richter m\u00fcssen sich nur um diesen Formfehler k\u00fcmmern, wenn eine Partei dies verlangt. Bekommt der B\u00fcrger die Verj\u00e4hrung nicht mit und zahlt, bleibe das Geld beim Staat, sagt Jurist K\u00f6ster. Der Insolvenzspezialist geh\u00f6rt zu den Top-Anw\u00e4lten, die es in unsere Auswahlliste f\u00fcr Insolvenzrecht und Restrukturierung schafften\u00a0<em>(siehe Tabellen im separaten Management-Blog-Beitrag)<\/em>. Seine Branche ist gut besch\u00e4ftigt, die Zahl der Insolvenzen d\u00fcrfte in diesem Jahr die des Finanzkrisenjahrs 2008 toppen.<\/p>\n<\/div>\n<\/div>\n<div><span style=\"color: #000000;font-weight: bold\">Gerichtsurteile st\u00e4rken Betroffenen den R\u00fccken<\/span><\/div>\n<div>\n<p>Entscheidend f\u00fcr die Fristen bei der Coronar\u00fcckzahlung ist das Datum der Schlussabrechnung, in deren Verlauf Unternehmen vorrechneten, was die staatlich erzwungenen Schlie\u00dfungen sie gekostet hatten. Die Beh\u00f6rde entschied dann, ob sie das Geld zur\u00fcckzahlen mussten. Ein Prozedere, von dem keine Rede war, als die Politik die Coronasoforthilfen verk\u00fcndet hatte.<\/p>\n<\/div>\n<div class=\"iqdcontainer ng-star-inserted iqdad\" data-device=\"desktop\" data-placement=\"pos_2\">\n<div id=\"iqadtile4\" class=\"iqlabel iqlabel-left iqlabel-stdtxt iqadtile-space-tb iqdad\" data-placement=\"pos_2\" data-google-query-id=\"CLfC86jF6ZQDFY0nBgAdpcwICQ\">\n<div id=\"google_ads_iframe_\/183,22445232565\/iqwiwo\/erfolg\/management\/artikel_1__container__\">Das Urteil k\u00f6nnte manchem Kleinbetrieb, Freiberufler oder Solo-Selbstst\u00e4ndigen Hoffnung machen. Viele sind durch sp\u00e4te R\u00fcckforderungen auf Basis erst nachtr\u00e4glich festgelegter Kriterien in Schwierigkeiten geraten. Weil die Beh\u00f6rden die endg\u00fcltigen Bescheide erst nach und nach abarbeiten, \u00aderlebt so mancher eine b\u00f6se \u00dcberraschung. Der Maschinenbauer Ballweg\u2006+\u2006B\u00f6ttner aus dem badischen Walld\u00fcrn, Modehaus Jeske aus Greifswald oder die Fitnesskette Orthofit etwa nannten die R\u00fcckzahlungen ausdr\u00fccklich als Insolvenzursache.<\/div>\n<div><\/div>\n<\/div>\n<\/div>\n<div>\n<h1>Experten warnen vor Insolvenzwelle<\/h1>\n<\/div>\n<div>\n<p>Viele sterben aber still, so wie der Accessoires-H\u00e4ndler auf der D\u00fcsseldorfer K\u00f6, der nach 30 Jahren seinen Laden schlie\u00dft und sein Privathaus verkauft \u2013 um die sechsstellige R\u00fcckforderung \u00fcberweisen zu k\u00f6nnen. Weil die Beh\u00f6rde im Lockdown keine klaren Regeln verk\u00fcndet habe, seien die R\u00fcckforderungen f\u00fcr ihn unvorhersehbar gewesen, sagt er. Angesichts h\u00f6herer Mieten und weniger Kunden habe er keine R\u00fccklagen bilden k\u00f6nnen.<\/p>\n<\/div>\n<div>\n<p>\u201eEine Insolvenz hat immer mehrere Gr\u00fcnde\u201c, sagt Anwalt K\u00f6sters. So erledigt der Corona-Bumerang Firmen, deren Eigenkapital aufgezehrt ist, und die unter der Konjunktur und teurer Energie leiden, sagt Patrick-Ludwig Hantzsch von der Wirtschaftsauskunftei Creditreform. Viele Unternehmen m\u00fcssen nicht einmal Insolvenz anmelden und tauchen nicht in der Statistik auf. Sie geben einfach auf und liquidieren. R\u00fcckforderungsbescheide belasten zurzeit vor allem Gastro\u00adnomen und Einzelh\u00e4ndler, so Hantzsch.<\/p>\n<\/div>\n<div>\n<p>Ein Urteil mit \u201eSignalwirkung\u201c, so Anwalt Niko H\u00e4rting, f\u00e4llte gerade der Verwaltungsgerichtshof \u00adBaden-W\u00fcrttemberg (Aktenzeichen 14 S 1869\/24). In einem Musterverfahren hatte die Stuttgarter Kanzlei von Buttlar f\u00fcr einen Friseurmeister und \u00fcber 1000 andere Kl\u00e4ger gegen die R\u00fcckforderungsbescheide geklagt. Mit Erfolg: \u201eEs kann nicht auf einmal eine Nachhineinbetrachtung herangezogen werden, von der zum Zeitpunkt der Antragstellung keine Rede war\u201c, bremsten die Richter die Beh\u00f6rde ein.<\/p>\n<\/div>\n<div class=\"iqdcontainer ng-star-inserted iqdad\" data-device=\"desktop\" data-placement=\"pos_3\">\n<div id=\"iqadtile99\" class=\"iqlabel iqlabel-left iqlabel-stdtxt iqadtile-space-tb iqdad\" data-placement=\"pos_3\" data-google-query-id=\"CMTFiqnF6ZQDFWCJfAYdIZoedA\"><\/div>\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.faktenkontor.de\/pressemeldungen\/blogger-relevanzindex-das-sind-deutschlands-top-100-blogs\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-680063\" src=\"https:\/\/149798077.v2.pressablecdn.com\/management\/files\/2022\/06\/Wiwo.top_.10.blog_.2022.Blogger-Relevanzindex_Top-10-Blogs-2022-227x300.jpg\" alt=\"\" width=\"227\" height=\"300\" srcset=\"https:\/\/blog.wiwo.de\/management\/files\/2022\/06\/Wiwo.top_.10.blog_.2022.Blogger-Relevanzindex_Top-10-Blogs-2022-227x300.jpg 227w, https:\/\/blog.wiwo.de\/management\/files\/2022\/06\/Wiwo.top_.10.blog_.2022.Blogger-Relevanzindex_Top-10-Blogs-2022.jpg 492w\" sizes=\"auto, (max-width: 227px) 100vw, 227px\" \/><\/a><\/p>\n<div id=\"main\">\n<div id=\"primary\">\n<div id=\"content\" role=\"main\">\n<article id=\"post-679588\" class=\"post-679588 post type-post status-publish format-standard hentry category-allgemein tag-arbeitsbedingung tag-arbeitsklima tag-betriebsklima tag-big-quit tag-ey-ernst-young tag-fachkraftemangel tag-gehalt tag-great-resignation tag-jobwechsel tag-kundigung tag-kuendigungsabsicht tag-loehne tag-umfrage\">\n<div class=\"entry-content\">\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.presseportal.de\/pm\/52884\/5255623\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-676731\" src=\"https:\/\/149798077.v2.pressablecdn.com\/management\/files\/2021\/06\/bloggerinnen.2021.neu_-300x212.jpg\" alt=\"\" width=\"300\" height=\"212\" srcset=\"https:\/\/blog.wiwo.de\/management\/files\/2021\/06\/bloggerinnen.2021.neu_-300x212.jpg 300w, https:\/\/blog.wiwo.de\/management\/files\/2021\/06\/bloggerinnen.2021.neu_-424x300.jpg 424w, https:\/\/blog.wiwo.de\/management\/files\/2021\/06\/bloggerinnen.2021.neu_.jpg 650w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Copyright: @Claudia T\u00f6dtmann. Alle Rechte vorbehalten.\u00a0<\/strong><\/p>\n<p><strong>Kontakt f\u00fcr Nutzungsrechte: claudia.toedtmann@wiwo.de<\/strong><\/p>\n<p><strong>Alle inhaltlichen Rechte des Management-Blogs von Claudia T\u00f6dtmann liegen bei der Blog-Inhaberin. Jegliche Nutzung der Inhalte bedarf der ausdr\u00fccklichen Genehmigung.<\/strong><\/p>\n<\/div>\n<p><strong>Um den Lesefluss nicht zu behindern, wird in Management-Blog-Texten nur die m\u00e4nnliche Form genannt, aber immer sind die weibliche und andere Formen gleicherma\u00dfen mit gemeint.<\/strong><\/p>\n<\/article>\n<\/div>\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Staat fordert Coronahilfen zur\u00fcck \u2013 so wehren sich Betriebe Will der Staat unerwartet pl\u00f6tzlich Coronahilfen zur\u00fcck, kann dies Kleinbetriebe ruinieren. Anw\u00e4lte zeigen, wie sie sich wehren. (zuerst erschienen in der gedruckten WirtschaftsWoche am 29.05.2026) Foto: Ulf K.\/Sepia Drei Jahre nachdem &hellip; <a href=\"https:\/\/blog.wiwo.de\/management\/2026\/06\/03\/wenn-rueckforderungen-von-coronahilfen-zum-sargnagel-fuer-haendler-und-unternehmen-werden\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":19,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[3573,12684,3396,12697,3395,10208,12699,12696,12700,12701,12698],"class_list":["post-688107","post","type-post","status-publish","format-standard","hentry","category-allgemein","tag-creditreform","tag-coronahilfen","tag-insolvenzrecht","tag-koesterberner","tag-malte-koster","tag-niko-haerting","tag-patrick-ludwig-hantzsch","tag-rueckforderungen","tag-verwaltungsgericht-koeln","tag-verwaltungsgerichtshof-baden-wuerttemberg","tag-vg-koeln"],"_links":{"self":[{"href":"https:\/\/blog.wiwo.de\/management\/wp-json\/wp\/v2\/posts\/688107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.wiwo.de\/management\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.wiwo.de\/management\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.wiwo.de\/management\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.wiwo.de\/management\/wp-json\/wp\/v2\/comments?post=688107"}],"version-history":[{"count":2,"href":"https:\/\/blog.wiwo.de\/management\/wp-json\/wp\/v2\/posts\/688107\/revisions"}],"predecessor-version":[{"id":688109,"href":"https:\/\/blog.wiwo.de\/management\/wp-json\/wp\/v2\/posts\/688107\/revisions\/688109"}],"wp:attachment":[{"href":"https:\/\/blog.wiwo.de\/management\/wp-json\/wp\/v2\/media?parent=688107"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.wiwo.de\/management\/wp-json\/wp\/v2\/categories?post=688107"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.wiwo.de\/management\/wp-json\/wp\/v2\/tags?post=688107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}