{"id":681802,"date":"2023-03-07T15:07:33","date_gmt":"2023-03-07T14:07:33","guid":{"rendered":"https:\/\/blog.wiwo.de\/management\/?p=681802"},"modified":"2023-03-08T20:39:38","modified_gmt":"2023-03-08T19:39:38","slug":"fragebogen-nahaufnahme-mit-familienunternehmer-philipp-reisert-der-sich-bei-der-teambuilding-massnahme-flying-fox-gleich-acht-knochen-brach","status":"publish","type":"post","link":"https:\/\/blog.wiwo.de\/management\/2023\/03\/07\/fragebogen-nahaufnahme-mit-familienunternehmer-philipp-reisert-der-sich-bei-der-teambuilding-massnahme-flying-fox-gleich-acht-knochen-brach\/","title":{"rendered":"Fragebogen &#8222;Nahaufnahme&#8220; mit Familienunternehmer Philipp Reisert, der sich bei der Teambuilding-Ma\u00dfnahme Flying Fox gleich acht Knochen brach"},"content":{"rendered":"<h1><strong>Den Fragebogen &#8222;Nahaufnahme&#8220; beantwortet Philipp Reisert, Chef der\u00a0<\/strong>Gold- und Silberscheideanstalt C.Hafner, die sich neben dem Recycling von Edelmetallen auf Produkte und Dienstleistungen im Bereich der Edelmetalltechnologie spezialisiert hat. Das Traditionsunternehmen z\u00e4hlt nach eigenen Angaben zu den f\u00fchrenden Anbietern in Europa.<\/h1>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<div id=\"attachment_681803\" style=\"width: 660px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-681803\" class=\"size-full wp-image-681803\" src=\"https:\/\/blog.wiwo.de\/management\/files\/2023\/03\/reisert.neu_.jpg\" alt=\"\" width=\"650\" height=\"464\" srcset=\"https:\/\/blog.wiwo.de\/management\/files\/2023\/03\/reisert.neu_.jpg 650w, https:\/\/blog.wiwo.de\/management\/files\/2023\/03\/reisert.neu_-300x214.jpg 300w, https:\/\/blog.wiwo.de\/management\/files\/2023\/03\/reisert.neu_-420x300.jpg 420w\" sizes=\"auto, (max-width: 650px) 100vw, 650px\" \/><p id=\"caption-attachment-681803\" class=\"wp-caption-text\">Philipp Reisert (Foto: PR\/C.Hafner)<\/p><\/div>\n<p>&nbsp;<\/p>\n<p><strong>Erkl\u00e4ren Sie in einem Satz, was Ihr Unternehmen tut.<\/strong><\/p>\n<p>Wir bei C.Hafner gewinnen aus Abf\u00e4llen Edelmetalle, die wir zu Halbzeugen und Komponenten weiterverarbeiten.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Womit beginnt Ihr Tag?<\/strong><\/p>\n<p>Mein Tag startet um 5.50 Uhr mit dem Zubereiten des Fr\u00fchst\u00fccks f\u00fcr meine Familie. Am Vorabend d\u00fcrfen sich meine Frau und meine beiden Kinder w\u00fcnschen, was sie gerne essen m\u00f6chten und ich bereite dann jedem sein individuelles Fr\u00fchst\u00fcck zu. Meistens gibt es M\u00fcsli, Porridge oder Brot mit Marmelade, manchmal auch Pfannkuchen.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Was unterscheidet Sie von anderen im Auftreten und im Behave im Job?<\/strong><\/p>\n<p>Ich starte meinen Tag im B\u00fcro damit, dass ich erstmal f\u00fcr eine Weile verschwinde. Daf\u00fcr habe ich mein pers\u00f6nliches Refugium, ein Zimmer neben meinem B\u00fcro mit einem Sofa und Sessel. Dorthin ziehe ich mich zur\u00fcck und lese in Ruhe meine Agenda f\u00fcr den Tag sowie Zeitungen \u2013 am liebsten die &#8222;Pforzheimer Zeitung&#8220; und die &#8222;Frankfurter Allgemeine Zeitung&#8220;, um mich regional und weltweit auf den neuesten Stand zu bringen. Das bringt mir den n\u00f6tigen Schwung f\u00fcr den Tag.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>&#8230; und was w\u00fcrden Ihre Mitarbeiter darauf antworten?<\/strong><\/p>\n<p>Meine Assistentin am\u00fcsiert sich immer dar\u00fcber, dass ich ausschlie\u00dflich mit meinem F\u00fcller schreibe, den ich zu meinem Abschied, nach zehnj\u00e4hriger Amtszeit als Pr\u00e4sident des Bundesverbandes Schmuck und Uhren vom Verband geschenkt bekommen habe. Au\u00dferdem bin ich sehr speziell, wenn es um Kaffee geht und habe meine eigene Kaffeemaschine im B\u00fcro.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Tee oder Kaffee?<\/strong><\/p>\n<p>Beides! Morgens zu Hause trinke ich erstmal einen gr\u00fcnen Tee, vormittags im B\u00fcro einen Cappuccino und nach dem Mittagessen am liebsten einen Espresso.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Ihr Spitzname ist&#8230;?<\/strong><\/p>\n<p>Rumsdi, weil es immer irgendwie laut ist, wenn ich einen Raum betrete.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Verraten Sie eine Marotte.<\/strong><\/p>\n<p>Ich trage Hemden immer mit Manschettenkn\u00f6pfen. Ich finde, Manschettenkn\u00f6pfe sind eines der wenigen Schmuckst\u00fccke, die M\u00e4nner tragen k\u00f6nnen &#8211; abgesehen von einer Uhr und dem Ehering.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Was bringt Sie in Harnisch?<\/strong><\/p>\n<p>Wenn jemand versucht, mich herum zu kommandieren. Das mochte ich schon als Kind nicht.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>&#8230; und was bringt andere an Ihnen in Harnisch?<\/strong><\/p>\n<p>Wenn ich Dinge vergesse, die f\u00fcr mich pers\u00f6nlich nicht so relevant sind.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Was m\u00f6chten Sie gerne in Rente machen?<\/strong><\/p>\n<p>Das ist einfach! Eine <a href=\"https:\/\/de.wikipedia.org\/wiki\/Permakultur\">Permakultur<\/a>-Landwirtschaft auf meinem eigenen Hof betreiben.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Was sch\u00e4tzen Sie an anderen Menschen am meisten?<\/strong><\/p>\n<p>Wenn sie mit Intelligenz und Kreativit\u00e4t neue Wege gehen und in der Lage sind, andere zu inspirieren, diese zu beschreiten oder selbst welche zu finden.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Auf welche drei Dinge k\u00f6nnten Sie niemals verzichten?<\/strong><\/p>\n<p>Unser Haus, das mein Urgro\u00dfvater im Jahr 1913 erbaut hat, meine Laufschuhe und mein Handy, weil sich darauf meine Musik befindet.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Was war Ihr peinlichster Moment?<\/strong><\/p>\n<p>Mir f\u00e4llt keiner ein. Ich meine, dass jemandem nur dann etwas peinlich sein kann, wenn man nicht gen\u00fcgend Selbstvertrauen und manchmal auch Selbstironie hat.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Auf welches Erlebnis h\u00e4tten Sie lieber verzichtet?<\/strong><\/p>\n<p>Das war mein Sturz in die Tiefe in Pontresina, in der Schweiz. Dort war ich auf einem Management-Seminar und eine Teambuilding-Aktivit\u00e4t war Flying Fox, bei dem man an einem Drahtseil befestigt wird und im scheinbaren Sturzflug von einer Klippe Richtung Boden gleitet. Leider war der Sturzflug bei mir nicht nur scheinbar. Die Mitarbeiter der Anlage hatten mich nicht korrekt gesichert und ich bin 15 Meter in die Tiefe gest\u00fcrzt. Direkt auf einen zugefrorenen Bach und dort ins Eis eingebrochen. Wie durch ein Wunder habe ich mir dabei nur acht Knochen gebrochen und bin ansonsten unbeschadet davongekommen.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Wenn Sie f\u00fcr einen Tag den Job von jemand anderem \u00fcbernehmen k\u00f6nnten &#8211; welcher w\u00e4re das?<\/strong><\/p>\n<p>Ganz klar: Chefredakteur der &#8222;Bild&#8220;-Zeitung. Das war schon immer mein Traum! Ich finde es unglaublich spannend derjenige zu sein, der entscheidet, was die Leute in Deutschland morgens am Fr\u00fchst\u00fcckstisch lesen, ihre Meinung zu bilden und ihre Emotionen zu sch\u00fcren.<\/p>\n<div id=\"attachment_681804\" style=\"width: 497px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-681804\" class=\"size-full wp-image-681804\" src=\"https:\/\/blog.wiwo.de\/management\/files\/2023\/03\/reisert.2.Gegenstand-Buero-e1678196602108.jpg\" alt=\"\" width=\"487\" height=\"362\" srcset=\"https:\/\/blog.wiwo.de\/management\/files\/2023\/03\/reisert.2.Gegenstand-Buero-e1678196602108.jpg 487w, https:\/\/blog.wiwo.de\/management\/files\/2023\/03\/reisert.2.Gegenstand-Buero-e1678196602108-300x223.jpg 300w, https:\/\/blog.wiwo.de\/management\/files\/2023\/03\/reisert.2.Gegenstand-Buero-e1678196602108-404x300.jpg 404w\" sizes=\"auto, (max-width: 487px) 100vw, 487px\" \/><p id=\"caption-attachment-681804\" class=\"wp-caption-text\">(Foto: Privat)<\/p><\/div>\n<p><b>&#8222;<\/b>Diese Statue habe ich von einem guten Freund zum Einstieg bei C.Hafner geschenkt bekommen und sie steht seitdem auf meinem Schreibtisch&#8220;, erz\u00e4hlt Philipp Reisert. &#8222;F\u00fcr mich bedeutet es, dass jeder einzelne die Welt bewegen kann: Er kann sie vom Sockel schieben oder sie bewahren \u2013 das ist jedem selbst \u00fcberlassen, aber egal wof\u00fcr man sich entscheidet, jeder von uns ist dazu in der Lage einen echten Unterschied zu bewirken.&#8220;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<div id=\"main\">\n<div id=\"primary\">\n<div id=\"content\" role=\"main\">\n<article id=\"post-680760\" class=\"post-680760 post type-post status-publish format-standard hentry category-allgemein tag-auslander tag-bezuege tag-dax tag-dax-vorstande tag-deutsche-bank tag-deutsche-schutzvereinigung-fur-wertpapierbesitz-dsw tag-frauen tag-linde tag-quiagen tag-technische-universitaet-muenchen-tum tag-vorstandinnen\">\n<div class=\"entry-content\">\n<p><a href=\"https:\/\/www.faktenkontor.de\/pressemeldungen\/blogger-relevanzindex-das-sind-deutschlands-top-100-blogs\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-680063\" src=\"https:\/\/149798077.v2.pressablecdn.com\/management\/files\/2022\/06\/Wiwo.top_.10.blog_.2022.Blogger-Relevanzindex_Top-10-Blogs-2022-227x300.jpg\" alt=\"\" width=\"227\" height=\"300\" srcset=\"https:\/\/blog.wiwo.de\/management\/files\/2022\/06\/Wiwo.top_.10.blog_.2022.Blogger-Relevanzindex_Top-10-Blogs-2022-227x300.jpg 227w, https:\/\/blog.wiwo.de\/management\/files\/2022\/06\/Wiwo.top_.10.blog_.2022.Blogger-Relevanzindex_Top-10-Blogs-2022.jpg 492w\" sizes=\"auto, (max-width: 227px) 100vw, 227px\" \/><\/a><\/p>\n<div id=\"main\">\n<div id=\"primary\">\n<div id=\"content\" role=\"main\">\n<article id=\"post-679588\" class=\"post-679588 post type-post status-publish format-standard hentry category-allgemein tag-arbeitsbedingung tag-arbeitsklima tag-betriebsklima tag-big-quit tag-ey-ernst-young tag-fachkraftemangel tag-gehalt tag-great-resignation tag-jobwechsel tag-kundigung tag-kuendigungsabsicht tag-loehne tag-umfrage\">\n<div class=\"entry-content\">\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.presseportal.de\/pm\/52884\/5255623\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-676731\" src=\"https:\/\/149798077.v2.pressablecdn.com\/management\/files\/2021\/06\/bloggerinnen.2021.neu_-300x212.jpg\" alt=\"\" width=\"300\" height=\"212\" srcset=\"https:\/\/blog.wiwo.de\/management\/files\/2021\/06\/bloggerinnen.2021.neu_-300x212.jpg 300w, https:\/\/blog.wiwo.de\/management\/files\/2021\/06\/bloggerinnen.2021.neu_-424x300.jpg 424w, https:\/\/blog.wiwo.de\/management\/files\/2021\/06\/bloggerinnen.2021.neu_.jpg 650w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Copyright: @Claudia T\u00f6dtmann. Alle Rechte vorbehalten.\u00a0<\/strong><\/p>\n<p><strong>Kontakt f\u00fcr Nutzungsrechte: claudia.toedtmann@wiwo.de<\/strong><\/p>\n<p><strong>Alle inhaltlichen Rechte des Management-Blogs von Claudia T\u00f6dtmann liegen bei der Blog-Inhaberin. Jegliche Nutzung der Inhalte bed\u00fcrfen der ausdr\u00fccklichen Genehmigung.<\/strong><\/p>\n<\/div>\n<p><strong>Um den Lesefluss nicht zu behindern, wird in Management-Blog-Texten nur die m\u00e4nnliche Form genannt, aber immer sind die weibliche und andere Formen gleicherma\u00dfen mit gemeint.<\/strong><\/p>\n<\/article>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"at-below-post addthis_tool\" data-url=\"https:\/\/blog.wiwo.de\/management\/2022\/09\/01\/680577\/\" data-title=\"Quiet Quitting: Warum Arbeitgeber schlaflose N\u00e4chte haben und nichts gegen das l\u00e4stige Ph\u00e4nomen tun k\u00f6nnen, erkl\u00e4rt Willms Buhse\" data-description=\"Quiet Quitting - Gastkommentar von Internet-Ikone Willms Buhse: Grade soviel arbeiten, dass man nicht gek\u00fcndigt werden kann Aus den USA kommt das Modewort, das Arbeitgeber pl\u00f6tzlich aufschreckt: Quiet Quitting, ruhiges Au. Offenbar glaubten bis dato Arbeitgeber, dass sie zwar f\u00fcr einen bestimmten Betrag eine bestimmte Zahl an Arbeitsstunden einkaufen - aber trotzdem immer eine Schippe...\">\n<div id=\"atstbx\" class=\"at-share-tbx-element at-share-tbx-native addthis_default_style addthis_20x20_style addthis-smartlayers addthis-animated at4-show\">\n<div class=\"atclear\"><\/div>\n<\/div>\n<div id=\"atstbx\" class=\"at-share-tbx-element at-share-tbx-native addthis_default_style addthis_20x20_style addthis-smartlayers at4-visually-hidden\"><\/div>\n<\/div>\n<\/div>\n<\/article>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Den Fragebogen &#8222;Nahaufnahme&#8220; beantwortet Philipp Reisert, Chef der\u00a0Gold- und Silberscheideanstalt C.Hafner, die sich neben dem Recycling von Edelmetallen auf Produkte und Dienstleistungen im Bereich der Edelmetalltechnologie spezialisiert hat. Das Traditionsunternehmen z\u00e4hlt nach eigenen Angaben zu den f\u00fchrenden Anbietern in Europa. &hellip; <a href=\"https:\/\/blog.wiwo.de\/management\/2023\/03\/07\/fragebogen-nahaufnahme-mit-familienunternehmer-philipp-reisert-der-sich-bei-der-teambuilding-massnahme-flying-fox-gleich-acht-knochen-brach\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":19,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[11268,6781,11267],"class_list":["post-681802","post","type-post","status-publish","format-standard","hentry","category-allgemein","tag-c-hafner","tag-fagebogen-nahaufnahme","tag-philipp-reisert"],"_links":{"self":[{"href":"https:\/\/blog.wiwo.de\/management\/wp-json\/wp\/v2\/posts\/681802","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.wiwo.de\/management\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.wiwo.de\/management\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.wiwo.de\/management\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.wiwo.de\/management\/wp-json\/wp\/v2\/comments?post=681802"}],"version-history":[{"count":5,"href":"https:\/\/blog.wiwo.de\/management\/wp-json\/wp\/v2\/posts\/681802\/revisions"}],"predecessor-version":[{"id":681813,"href":"https:\/\/blog.wiwo.de\/management\/wp-json\/wp\/v2\/posts\/681802\/revisions\/681813"}],"wp:attachment":[{"href":"https:\/\/blog.wiwo.de\/management\/wp-json\/wp\/v2\/media?parent=681802"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.wiwo.de\/management\/wp-json\/wp\/v2\/categories?post=681802"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.wiwo.de\/management\/wp-json\/wp\/v2\/tags?post=681802"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}