{"id":640368,"date":"2011-03-01T02:10:52","date_gmt":"2011-03-01T00:10:52","guid":{"rendered":"http:\/\/www.wiwo.de\/blogs\/management\/?p=640368"},"modified":"2011-03-01T02:10:52","modified_gmt":"2011-03-01T00:10:52","slug":"verwirrte-manager","status":"publish","type":"post","link":"https:\/\/blog.wiwo.de\/management\/2011\/03\/01\/verwirrte-manager\/","title":{"rendered":"Verwirrte Manager"},"content":{"rendered":"<p>Aus dem Hause Booz &amp; Company kommt eine ungew\u00f6hnliche wie erschreckende Umfrage: Jeder zweite Manager (52 Prozent) bezweifelt die Strategie seiner eigenen Firma. Nur 13 Prozent &#8222;folgen einer stimmigen strategischen Ausrichtung&#8220; und 64 Prozent der Top-Manager zerreissen widerspr\u00fcchliche Priorit\u00e4ten. Diese Ergebnisse zeigten sich nach einer Befragung von 1800 Managern weltweit.<\/p>\n<p><strong>Manager verzetteln sich<\/strong><\/p>\n<p>So weit so tragisch. Doch es kommt noch dicker: Sie verzetteln sich. Die Unternehmenslenker konzentrieren sich nicht auf ein Ziel, sondern verfolgen mehrere Optionen gleichzeitig &#8211; um das Risiko zu streuen. erreicht wird so aber das Gegenteil: &#8222;Acht von zehn Managern haben die Erfahrung gemacht, dass die vermeintliche Wachstumsstrategie im Endeffekt zu Verlusten gef\u00fchrt hat&#8220;, berichtet Klaus-Peter Gushurst, Deutschlandchef von Booz &amp; Company. Und 43 Prozent der Unternehmen haben keine differenzierende Strategie, die sich durch alle Entscheidungsprozesse zieht.<\/p>\n<p><strong>Positiv-Beispiele Pfizer, Amazon und Procter &amp; Gamble<\/strong><\/p>\n<p>Der M\u00fcnchner kritisiert: Die Top-Manager greifen zu schnell nach neuen Gesch\u00e4ftschancen. Die Erkenntnis des ausgewiesenen Automotive-Experten ist vielmehr, dass &#8222;Wachstum aufgrund einer konsequenten Strategie entsteht und nicht aufgrund einzelner Initiativen.&#8220; Positivbeispiele sind laut Gushurst die gro\u00dfe Namen Pfizer, Amazon oder Procter &amp; Gamble. Nur bei 13 Prozent der untersuchten Unternehmen schaffen es, ihre F\u00e4higkeiten und ihre Marktposition strategisch eng aufeinander abzustimmen &#8211; und die werden belohnt mit \u00fcberdurchschnittlicher Profitabilit\u00e4t.<\/p>\n<p><strong>Herkules-Aufgabe: Die Mitarbeiter \u00fcberzeugen und mitnehmen<\/strong><\/p>\n<p>Erstaunlich ist, mit welcher Klarheit die F\u00fchrungseliten auch ihre eigenen Fehler ausmachen. 50 Prozent meinen, dass sie die Strategie den Mitarbeitern nicht \u00fcberzeugend kommunizieren.<\/p>\n<p>Selbst wie sie ihre Arbeitszeit einteilen, gef\u00e4llt etlichen Managern selbst nicht: 26 Prozent der Befragten verbringen &#8211; so sagen sie selbst &#8211; zu viel Zeit damit, Projektantr\u00e4ge zu pr\u00fcfen, die nicht zur Gesamtzielsetzung passen.<\/p>\n<p><strong>Je mehr Ziele desto unwahrscheinlicher der Erfolg<\/strong><\/p>\n<p>Was ist nun das Geheimnis des Erfolgs? Die einfache Formel heisst &#8222;weniger ist mehr&#8220;. 44 Prozent der Befragten aus Unternehmen mit maximal drei strategischen Priorit\u00e4ten sind profitabler als der Marktdurchschnitt: Das kann nicht mal jeder dritte Manager von sich sagen, der mehr als zehn Priorit\u00e4ten verfolgen muss.<\/p>\n<p>Dabei wissen die Manager durchaus, was ihre gr\u00f6\u00dften Herausforderungen sind:<\/p>\n<p>&#8211; Die Abstimmung von t\u00e4glichen Entscheidungen beziehungsweise Ressourcen-Eins\u00e4tzen auf die Gesamtstrategie (56 Prozent)<\/p>\n<p>&#8211; Die z\u00fcgige Umsetzung strategischer Entscheidungen (54 Prozent) und<\/p>\n<p>&#8211; die Festlegung einer klaren und differenzierenden Strategie (50 Prozent).<\/p>\n<p>Sie m\u00fcssen sie nur noch erreichen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Arme Unternehmenslenker: Sie verzetteln sich, k\u00f6nnen ihre eigenen Mitarbeiter nicht \u00fcberzeugen und sie werden zerrieben von widerspr\u00fcchlichen Priorit\u00e4ten &#8211; das ist ihnen bewusst und sie geben es auch zu. Das zeigt eine internationale Umfrage unter Top-Managern von der Unternehmensberatung Booz &amp; Company. Das Fazit: Die F\u00fchrungseliten \u00fcbersehen, dass die eigentlichen Hindernisse innerhalb ihrer eigenen Firma liegen. <a href=\"https:\/\/blog.wiwo.de\/management\/2011\/03\/01\/verwirrte-manager\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":19,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[179,1056,1160],"class_list":["post-640368","post","type-post","status-publish","format-standard","hentry","category-allgemeines","tag-booz-company","tag-top-manager","tag-weltweite-umfrage"],"_links":{"self":[{"href":"https:\/\/blog.wiwo.de\/management\/wp-json\/wp\/v2\/posts\/640368","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.wiwo.de\/management\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.wiwo.de\/management\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.wiwo.de\/management\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.wiwo.de\/management\/wp-json\/wp\/v2\/comments?post=640368"}],"version-history":[{"count":0,"href":"https:\/\/blog.wiwo.de\/management\/wp-json\/wp\/v2\/posts\/640368\/revisions"}],"wp:attachment":[{"href":"https:\/\/blog.wiwo.de\/management\/wp-json\/wp\/v2\/media?parent=640368"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.wiwo.de\/management\/wp-json\/wp\/v2\/categories?post=640368"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.wiwo.de\/management\/wp-json\/wp\/v2\/tags?post=640368"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}