{"id":45533,"date":"2019-09-03T07:30:18","date_gmt":"2019-09-03T05:30:18","guid":{"rendered":"https:\/\/blog.wiwo.de\/look-at-it\/?p=45533"},"modified":"2019-09-03T10:24:03","modified_gmt":"2019-09-03T08:24:03","slug":"datenchaos-in-unternehmen-im-schnitt-mehr-als-20-000-dateien-pro-mitarbeiter","status":"publish","type":"post","link":"https:\/\/blog.wiwo.de\/look-at-it\/2019\/09\/03\/datenchaos-in-unternehmen-im-schnitt-mehr-als-20-000-dateien-pro-mitarbeiter\/","title":{"rendered":"Datenchaos in Unternehmen: Im Schnitt mehr als 20.000 Dateien pro Mitarbeiter"},"content":{"rendered":"<p><strong>Jeder PC-Nutzer in deutschen Firmen besitzt durchschnittlich mehr als 20.000 Dateien in Filesystemen. Dies verursacht massive Schwierigkeiten und Kosten.<\/strong><\/p>\n<p>Der Berliner IT-Spezialdienstleister Aikux.com GmbH hat rund 400 IT-Projekte aus den Jahren 2017 bis 2019 rund um Unternehmensdaten und Zugriffsrechte ausgewertet und daraus wichtige Erfahrungen zur Datenkultur in deutschen Firmen abgeleitet. Neben den Voumina wurde hierbei auch der Status der gespeicherten Dateien betrachtet.<\/p>\n<p>Wichtigster und zentraler Befund: Jeder PC-Mitarbeiter in deutschen Unternehmen besitzt durchschnittlich mehr als 20.000 Dateien in Filesystemen. Dies verursacht mittlerweile massive Schwierigkeiten &#8211; auch finanzieller Natur.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-45561\" style=\"border: 0px\" src=\"https:\/\/blog.wiwo.de\/look-at-it\/files\/2019\/09\/ArbeitszeitverlustDaten1.jpg\" alt=\"\" width=\"600\" height=\"320\" srcset=\"https:\/\/blog.wiwo.de\/look-at-it\/files\/2019\/09\/ArbeitszeitverlustDaten1.jpg 600w, https:\/\/blog.wiwo.de\/look-at-it\/files\/2019\/09\/ArbeitszeitverlustDaten1-300x160.jpg 300w, https:\/\/blog.wiwo.de\/look-at-it\/files\/2019\/09\/ArbeitszeitverlustDaten1-500x267.jpg 500w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>Dabei unterscheidet sich das Ausma\u00df der Problematik von Branche zu Branche. So legen etwa Hospit\u00e4ler ihre Daten prim\u00e4r in Krankenhausinformationssystemen ab und weisen mit durchschnittlich 5.000 bis 10.000 Dateien je PC-Mitarbeiter eher weniger Daten auf. Hier ist eher problematisch, dass hochsensible personenbezogene Daten im Umlauf und diese oft unzureichend gegen unbefugten Zugriff gesichert sind.<\/p>\n<p>In anderen Branchen kann diese Kennzahl mit 50.000 bis 100.000 Dateien auch einmal deutlich h\u00f6her liegen. Betrachtet wurde ausschlie\u00dflich das Standard-Filesystem auf den unternehmensinternen Servern. Unstrukturierte Daten in weiteren Ablageorten wie SharePoint, Cloud-Speichern und Exchange m\u00fcssen also noch hinzugerechnet werden.<\/p>\n<p>Doch nicht nur die enorme Anzahl gespeicherter Dateien stellt eine Herausforderung dar. So zeigt die Auswertung von Aikux, dass durchschnittlich nur 15 Prozent der Daten tats\u00e4chlich relevant sind. Die restlichen Objekte sind somit entweder Dark Data &#8211; das hei\u00dft: mit unbekanntem Wert f\u00fcrs Unternehmen &#8211; oder ROT-Data: Also redundant, obsolet oder trivial.<\/p>\n<p>Aus diesem Grund k\u00f6nnten 20 bis 40 Prozent aller Dokumente nach ihrer Erstellung und Weitergabe direkt wieder gel\u00f6scht werden. \u00dcber drei Viertel s\u00e4mtlicher Daten sind zudem \u00e4lter als zwei Jahre und damit h\u00f6chstwahrscheinlich veraltet. Erschwerend kommt hinzu, dass sich die Datenmenge alle zwei bis drei Jahre verdoppelt.<\/p>\n<p>Das Datenchaos ist nicht nur l\u00e4stig f\u00fcr die Mitarbeiter, es erzeugt gleichzeitig enorme finanzielle Sch\u00e4den. Im Durchschnitt verursacht die Intransparenz in den Dateisystemen einen Zeitaufwand von 30 bis 60 Minuten pro Mitarbeiter und Tag. Dieser entsteht nicht nur durch die langwierige Dateisuche, sondern auch durch die \u00fcberfl\u00fcssige Neuerstellung von bereits vorliegenden Dateien.<\/p>\n<p>Zus\u00e4tzliche Zeitverluste ergeben sich durch das Arbeiten auf einer falschen Version. F\u00fcr ein Unternehmen mit 1.000 Mitarbeitern resultiert hieraus &#8211; konservativ bewertet &#8211; ein j\u00e4hrlicher kalkulatorischer Verlust von 8 Millionen Euro.<\/p>\n<p>Weitere Zahlen &amp; Fakten zum Datenchaos in deutschen Unternehmen in der folgenden Infografik:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-45560\" style=\"border: 0px\" src=\"https:\/\/blog.wiwo.de\/look-at-it\/files\/2019\/09\/ArbeitszeitverlustDatenIG.jpg\" alt=\"\" width=\"560\" height=\"1626\" srcset=\"https:\/\/blog.wiwo.de\/look-at-it\/files\/2019\/09\/ArbeitszeitverlustDatenIG.jpg 560w, https:\/\/blog.wiwo.de\/look-at-it\/files\/2019\/09\/ArbeitszeitverlustDatenIG-103x300.jpg 103w, https:\/\/blog.wiwo.de\/look-at-it\/files\/2019\/09\/ArbeitszeitverlustDatenIG-353x1024.jpg 353w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><\/p>\n<p style=\"text-align: center\">Quelle: <a href=\"https:\/\/www.aikux.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Aikux.com<\/a><\/p>\n<p><strong>Verwandte Artikel:<\/strong><\/p>\n<p><a href=\"https:\/\/blog.wiwo.de\/look-at-it\/2019\/05\/22\/deutsche-unternehmen-erhalten-pro-investiertem-euro-ins-daten-management-213-euro-zurueck\/\" target=\"_blank\" rel=\"noopener noreferrer\">Unternehmen erhalten pro investiertem Euro ins Daten-Management 2,13\u20ac zur\u00fcck<\/a><\/p>\n<p><a href=\"https:\/\/blog.wiwo.de\/look-at-it\/2019\/05\/09\/4-von-5-deutschen-unternehmen-mit-it-ausfall-im-vergangenen-jahr-ein-drittel-mit-datenverlusten\/\" target=\"_blank\" rel=\"noopener noreferrer\">4 von 5 deutschen Firmen mit IT-Ausfall im vergangenen Jahr; 1\/3 mit Datenverlust<\/a><\/p>\n<p><a href=\"https:\/\/blog.wiwo.de\/look-at-it\/2018\/11\/14\/fast-10-milliarden-gestohlene-oder-verlorene-datensaetze-seit-2013\/\" target=\"_blank\" rel=\"noopener noreferrer\">Fast 10 Milliarden gestohlene oder verlorene Datens\u00e4tze seit 2013<\/a><\/p>\n<p><a href=\"https:\/\/blog.wiwo.de\/look-at-it\/2018\/11\/08\/sechs-von-zehn-unternehmen-sichern-die-eigenen-daten-nicht-ausreichend\/\" target=\"_blank\" rel=\"noopener noreferrer\">Sechs von zehn Unternehmen sichern die eigenen Daten nicht ausreichend<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jeder PC-Nutzer in deutschen Firmen besitzt durchschnittlich mehr als 20.000 Dateien in Filesystemen. Dies verursacht massive Schwierigkeiten und Kosten. Der Berliner IT-Spezialdienstleister Aikux.com GmbH hat rund 400 IT-Projekte aus den Jahren 2017 bis 2019 rund um Unternehmensdaten und Zugriffsrechte ausgewertet &hellip; <a href=\"https:\/\/blog.wiwo.de\/look-at-it\/2019\/09\/03\/datenchaos-in-unternehmen-im-schnitt-mehr-als-20-000-dateien-pro-mitarbeiter\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":16,"featured_media":45561,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[210,19],"class_list":["post-45533","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","tag-big-data","tag-datenschutz"],"_links":{"self":[{"href":"https:\/\/blog.wiwo.de\/look-at-it\/wp-json\/wp\/v2\/posts\/45533","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.wiwo.de\/look-at-it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.wiwo.de\/look-at-it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.wiwo.de\/look-at-it\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.wiwo.de\/look-at-it\/wp-json\/wp\/v2\/comments?post=45533"}],"version-history":[{"count":7,"href":"https:\/\/blog.wiwo.de\/look-at-it\/wp-json\/wp\/v2\/posts\/45533\/revisions"}],"predecessor-version":[{"id":45568,"href":"https:\/\/blog.wiwo.de\/look-at-it\/wp-json\/wp\/v2\/posts\/45533\/revisions\/45568"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.wiwo.de\/look-at-it\/wp-json\/wp\/v2\/media\/45561"}],"wp:attachment":[{"href":"https:\/\/blog.wiwo.de\/look-at-it\/wp-json\/wp\/v2\/media?parent=45533"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.wiwo.de\/look-at-it\/wp-json\/wp\/v2\/categories?post=45533"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.wiwo.de\/look-at-it\/wp-json\/wp\/v2\/tags?post=45533"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}